{"id":5290,"count":1,"description":"","link":"https:\/\/revistadospneus.com\/pt\/tag\/garrett-trucksport\/","name":"Garrett Trucksport","slug":"garrett-trucksport","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Garrett Trucksport - Revista dos Pneus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revistadospneus.com\/pt\/tag\/garrett-trucksport\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Garrett Trucksport - Revista dos Pneus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revistadospneus.com\/pt\/tag\/garrett-trucksport\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista dos Pneus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@revistapneus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/tag\\\/garrett-trucksport\\\/\",\"url\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/tag\\\/garrett-trucksport\\\/\",\"name\":\"Arquivo de Garrett Trucksport - Revista dos Pneus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/tag\\\/garrett-trucksport\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/tag\\\/garrett-trucksport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garrett Trucksport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/\",\"name\":\"Revista dos Pneus\",\"description\":\"Revista independente de pneus e servi\u00e7os r\u00e1pidos\",\"publisher\":{\"@id\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/#organization\",\"name\":\"Revista dos Pneus\",\"url\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/wp-content\\\/uploads\\\/logo2-1.png\",\"contentUrl\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/wp-content\\\/uploads\\\/logo2-1.png\",\"width\":216,\"height\":70,\"caption\":\"Revista dos Pneus\"},\"image\":{\"@id\":\"https:\\\/\\\/revistadospneus.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/revistapneus\",\"https:\\\/\\\/x.com\\\/revistapneus\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Garrett Trucksport - Revista dos Pneus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revistadospneus.com\/pt\/tag\/garrett-trucksport\/","og_locale":"pt_PT","og_type":"article","og_title":"Arquivo de Garrett Trucksport - Revista dos Pneus","og_url":"https:\/\/revistadospneus.com\/pt\/tag\/garrett-trucksport\/","og_site_name":"Revista dos Pneus","twitter_card":"summary_large_image","twitter_site":"@revistapneus","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/revistadospneus.com\/pt\/tag\/garrett-trucksport\/","url":"https:\/\/revistadospneus.com\/pt\/tag\/garrett-trucksport\/","name":"Arquivo de Garrett Trucksport - Revista dos Pneus","isPartOf":{"@id":"https:\/\/revistadospneus.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/revistadospneus.com\/pt\/tag\/garrett-trucksport\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/revistadospneus.com\/pt\/tag\/garrett-trucksport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/revistadospneus.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Garrett Trucksport"}]},{"@type":"WebSite","@id":"https:\/\/revistadospneus.com\/pt\/#website","url":"https:\/\/revistadospneus.com\/pt\/","name":"Revista dos Pneus","description":"Revista independente de pneus e servi\u00e7os r\u00e1pidos","publisher":{"@id":"https:\/\/revistadospneus.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/revistadospneus.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/revistadospneus.com\/pt\/#organization","name":"Revista dos Pneus","url":"https:\/\/revistadospneus.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/revistadospneus.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/revistadospneus.com\/pt\/wp-content\/uploads\/logo2-1.png","contentUrl":"https:\/\/revistadospneus.com\/pt\/wp-content\/uploads\/logo2-1.png","width":216,"height":70,"caption":"Revista dos Pneus"},"image":{"@id":"https:\/\/revistadospneus.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/revistapneus","https:\/\/x.com\/revistapneus","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]}]}},"_links":{"self":[{"href":"https:\/\/revistadospneus.com\/pt\/wp-json\/wp\/v2\/tags\/5290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistadospneus.com\/pt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/revistadospneus.com\/pt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/revistadospneus.com\/pt\/wp-json\/wp\/v2\/posts?tags=5290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}